{"id":5158,"date":"2023-03-02T02:35:04","date_gmt":"2023-03-02T02:35:04","guid":{"rendered":"https:\/\/climashield.com\/?p=5158"},"modified":"2025-09-05T23:56:27","modified_gmt":"2025-09-05T23:56:27","slug":"author-qa-born-to-climbs-zofia-reych","status":"publish","type":"post","link":"https:\/\/climashield.com\/fr\/author-qa-born-to-climbs-zofia-reych\/","title":{"rendered":"Questions-r\u00e9ponses de l&rsquo;auteur\u00a0: Zofia Reych de Born to Climb"},"content":{"rendered":"<p class=\"p1\">Nous avons rencontr\u00e9 l&rsquo;anthropologue et grimpeuse <a href=\"https:\/\/www.instagram.com\/upthatrock\/?hl=en\"><span class=\"s1\">Zofia Reych<\/span><\/a> dans la foul\u00e9e de son livre <a href=\"https:\/\/www.borntoclimb.net\/\"><span class=\"s1\">Born to Climb<\/span><\/a>, une lettre d&rsquo;amour \u00e0 l&rsquo;un des sports les plus dynamiques au monde. Au fil des pages de son livre, elle propose aux lecteurs un r\u00e9cit fascinant de l&rsquo;escalade, depuis ses origines jusqu&rsquo;\u00e0 ses moments charni\u00e8res, en passant par le clivage entre les sexes souvent n\u00e9glig\u00e9.<\/p>\n<p class=\"p1\">Poursuivez votre lecture pour en savoir plus sur l&rsquo;inspiration, le but et la passion qui sous-tendent la r\u00e9daction de ce livre.<\/p>\n<p class=\"p1\"><b>Parlez-moi un peu de votre parcours en \u00e9crivant ce livre.<\/b><\/p>\n<p class=\"p1\">Sc\u00e9nario de <a href=\"https:\/\/www.amazon.com\/CLIMBING-2021\/dp\/1839811528\/ref=tmm_hrd_swatch_0?_encoding=UTF8&amp;qid=1674293478&amp;sr=8-1\"><span class=\"s1\"><i>Born to Climb<\/i><\/span><\/a>\u00a0:<a href=\"https:\/\/www.amazon.com\/CLIMBING-2021\/dp\/1839811528\/ref=tmm_hrd_swatch_0?_encoding=UTF8&amp;qid=1674293478&amp;sr=8-1\"><span class=\"s1\"><i> Des pionniers de l&rsquo;escalade aux athl\u00e8tes olympiques<\/i><\/span><\/a> est devenu mon projet le plus long et le plus captivant. Pour les grimpeurs, les projets sont des itin\u00e9raires qui doivent \u00eatre revus \u00e0 de nombreuses reprises pour \u00eatre achev\u00e9s. Habituellement, un grimpeur choisit un projet trop difficile pour lui au moment o\u00f9 il rel\u00e8ve le d\u00e9fi. Ensuite, le processus qui consiste \u00e0 trouver la meilleure m\u00e9thode, \u00e0 devenir plus forts, etc. leur permet de monter de niveau et \u00e9ventuellement de terminer la mont\u00e9e. Mais on ne sait jamais vraiment si on y arrivera ou non, et cette incertitude apporte une dimension psychologique \u00e0 la projection. Dans un sens, chaque ascension devient une aventure, et c&rsquo;est ce que j&rsquo;ai ressenti en \u00e9crivant <i>Born to Climb<\/i>. Ce fut un voyage au cours duquel j&rsquo;ai probablement appris autant de choses sur moi-m\u00eame que sur l&rsquo;\u00e9criture d&rsquo;un livre.<\/p>\n<p class=\"p1\"><b>En quoi votre formation en anthropologie vous a-t-elle donn\u00e9 une perspective unique sur l&rsquo;escalade\u00a0?<\/b><\/p>\n<p class=\"p1\">Gr\u00e2ce \u00e0 mes \u00e9tudes en anthropologie, j&rsquo;ai pu envisager l&rsquo;escalade dans un contexte plus large, non pas comme une discipline autonome, mais comme une discipline fa\u00e7onn\u00e9e par une multitude de processus sociopolitiques. Sans contexte, les histoires de grimpeurs l\u00e9gendaires et les perc\u00e9es qu&rsquo;ils ont accomplies sont d\u00e9shumanis\u00e9es et presque d\u00e9nu\u00e9es de sens. \u00c0 titre d&rsquo;exemple, le d\u00e9veloppement acc\u00e9l\u00e9r\u00e9 de l&rsquo;escalade du Yosemite dans les ann\u00e9es 1950 et 1960 \u00e9tait directement li\u00e9 \u00e0 l&rsquo;air du temps\u00a0: r\u00e9volution culturelle, guerre du Vietnam, beatniks. Royal Robbins et Warren Harding ne pouvaient pas \u00eatre ce qu&rsquo;ils \u00e9taient sans ce contexte. Et l&rsquo;escalade ne serait pas ce qu&rsquo;elle est sans l&rsquo;histoire de l&rsquo;effacement des autochtones qui a conduit \u00e0 la cr\u00e9ation des grands parcs nationaux am\u00e9ricains. Ces \u00e9v\u00e9nements du pass\u00e9 continuent d&rsquo;avoir un impact sur ce qu&rsquo;est l&rsquo;escalade aujourd&rsquo;hui, et une approche anthropologique relie l&rsquo;exp\u00e9rience humaine individuelle \u00e0 cette vision plus large. Cela nous permet de comprendre pourquoi les choses sont comme elles sont.<\/p>\n<p class=\"p1\"><b>Qu&rsquo;avez-vous d\u00e9couvert au cours de vos recherches sur l&rsquo;histoire de l&rsquo;escalade qui vous a le plus int\u00e9ress\u00e9\u00a0?<\/b><\/p>\n<p class=\"p1\">Bien qu&rsquo;\u00e0 l&rsquo;origine l&rsquo;escalade ait \u00e9t\u00e9 domin\u00e9e par des hommes issus des classes sup\u00e9rieures, j&rsquo;ai \u00e9t\u00e9 surprise d&rsquo;apprendre que tr\u00e8s t\u00f4t, il y avait plus de femmes pr\u00e9sentes dans les montagnes et sur les rochers que nous ne le pensons. Cependant, contrairement \u00e0 leurs homologues masculins, elles n&rsquo;avaient g\u00e9n\u00e9ralement pas le temps, les ressources ou l&rsquo;envie de raconter leurs aventures. Les hommes, qui \u00e9taient membres de clubs et devaient affirmer leur statut social en impressionnant leurs pairs, faisaient des pr\u00e9sentations, \u00e9crivaient des articles, des livres, etc. C&rsquo;est un peu simplifi\u00e9, mais les femmes sont revenues de leurs exploits en plein air pour se retrouver en retard dans les t\u00e2ches m\u00e9nag\u00e8res. Des recherches sur des lettres, des journaux personnels, etc. r\u00e9v\u00e8lent aujourd&rsquo;hui qu&rsquo;il y avait des aventuri\u00e8res plus audacieuses que nous ne le pensons et l&rsquo;ampleur des obstacles sociaux qu&rsquo;elles ont d\u00fb surmonter.<\/p>\n<p class=\"p1\"><b>Qu&rsquo;esp\u00e9rez-vous dire aux gens sur l&rsquo;escalade dans ce livre qu&rsquo;ils ne connaissent peut-\u00eatre pas\u00a0?<\/b><\/p>\n<p class=\"p1\">Malgr\u00e9 sa riche histoire, sa multitude de disciplines, de comp\u00e9titions et de styles, l&rsquo;escalade doit rester une activit\u00e9 personnelle, ce qui signifie que chacun a le droit de le pratiquer de la mani\u00e8re qui lui convient le mieux, dans les limites fix\u00e9es par les pratiques de plein air durables.<\/p>\n<p class=\"p1\">En \u00e9crivant <i>Born to Climb<\/i>, j&rsquo;ai \u00e9prouv\u00e9 un sentiment de lib\u00e9ration en d\u00e9couvrant \u00e0 quel point cette discipline est vari\u00e9e et, dans une large mesure, arbitraire. La mise en perspective des r\u00e8gles et des objectifs stricts peut aider tout le monde, des nouveaux grimpeurs aux professionnels, \u00e0 d\u00e9couvrir ce que l&rsquo;escalade signifie r\u00e9ellement pour eux.<\/p>\n<p class=\"p1\"><b>Pouvez-vous nous parler un peu de la division entre les sexes en escalade\u00a0?<\/b><\/p>\n<p class=\"p1\">Les sports de plein air et d&rsquo;aventure tels que l&rsquo;escalade, le surf ou le VTT ont une histoire unique qui les distingue des disciplines traditionnelles de comp\u00e9tition. Ils ont d&rsquo;abord \u00e9t\u00e9 pratiqu\u00e9s dans des endroits recul\u00e9s et ont attir\u00e9 de nombreux personnages tr\u00e8s critiques \u00e0 l&rsquo;\u00e9gard de la culture dominante. Ils sont devenus un m\u00e9lange unique de machisme, souvent associ\u00e9 \u00e0 des exploits audacieux, mais aussi \u00e0 un certain degr\u00e9 d&rsquo;absence de st\u00e9r\u00e9otypes sexistes.<\/p>\n<p class=\"p1\">Aujourd&rsquo;hui, alors que l&rsquo;escalade s&rsquo;impose rapidement comme un sport de grand public, les grimpeuses impressionnent le public du monde entier par leur habilet\u00e9 et leur force. Mais le fait que leurs prouesses soient souvent surprenantes indique clairement que la soci\u00e9t\u00e9 a toujours tendance \u00e0 attendre moins des femmes.<\/p>\n<p class=\"p1\">La fa\u00e7on dont la fracture entre les sexes se manifeste dans l&rsquo;escalade est incroyablement complexe et fascinante, et son entr\u00e9e dans le discours dominant le rend encore plus vrai, avec \u00e0 la fois des espoirs et des craintes pour l&rsquo;avenir.<\/p>\n<p class=\"p1\"><b>Quelles ont \u00e9t\u00e9 vos exp\u00e9riences d&rsquo;escalade pr\u00e9f\u00e9r\u00e9es\u00a0? Et pourquoi aimez-vous ce sport\u00a0?<\/b><\/p>\n<p class=\"p1\">En fait, je profite de mes exp\u00e9riences d&rsquo;escalade pr\u00e9f\u00e9r\u00e9es ces derniers temps, sans pression de performance, sans attentes ni \u00e9motions n\u00e9gatives. J&rsquo;habite dans la for\u00eat de Fontainebleau, \u00e0 deux pas de chez moi pour faire de l&rsquo;escalade. Je sors et je grimpe chaque fois que c&rsquo;est possible. C&rsquo;est tout simplement incroyable.<\/p>\n<p class=\"p1\">L&rsquo;escalade n&rsquo;a pas toujours \u00e9t\u00e9 aussi simple pour moi, et j&rsquo;ai eu mon lot d&rsquo;aventures un peu dangereuses et de mauvaises d\u00e9cisions, et certaines d&rsquo;entre elles ont trouv\u00e9 leur place dans <i>Born to Climb<\/i>.<i> <\/i>Ces histoires contrebalancent le r\u00e9cit principal, qui raconte l&rsquo;histoire de grands grimpeurs accomplissant des choses extraordinaires, car m\u00eame si ce sont eux qui ont fa\u00e7onn\u00e9 le sport, les exp\u00e9riences d&rsquo;escalade peuvent \u00eatre exaltantes et bouleversantes, quel que soit le niveau.<\/p>\n<p class=\"p1\">Vous voulez en savoir plus\u00a0? Commandez votre exemplaire <a href=\"https:\/\/www.amazon.com\/Born-Climb-climbing-pioneers-athletes-ebook\/dp\/B09YN2ZKN9\/ref=sr_1_1?crid=34BG722WM2GGL&amp;keywords=zofia+reych&amp;qid=1656933229&amp;sprefix=zofia+reych,aps,242&amp;sr=8-1\"><span class=\"s2\">ici<\/span><\/a>.<\/p>\n","protected":false},"excerpt":{"rendered":"<p>Nous avons rencontr\u00e9 l&rsquo;anthropologue et grimpeuse Zofia Reych dans la foul\u00e9e de son livre Born to Climb, une lettre d&rsquo;amour \u00e0 l&rsquo;un des sports les plus dynamiques au monde. Au<a class=\"moretag\" \n href=\"https:\/\/climashield.com\/fr\/author-qa-born-to-climbs-zofia-reych\/\">&#8230;<\/a><\/p>\n","protected":false},"author":4,"featured_media":5166,"comment_status":"closed","ping_status":"closed","sticky":false,"template":"","format":"standard","meta":{"_acf_changed":false,"footnotes":""},"categories":[2277,1709],"tags":[55,629],"class_list":["post-5158","post","type-post","status-publish","format-standard","has-post-thumbnail","hentry","category-sustainability-fr","category-advocacy-fr","tag-climalife-fr","tag-get-outside-fr"],"acf":[],"yoast_head":"<!-- This site is optimized with the Yoast SEO plugin v28.0 - https:\/\/yoast.com\/product\/yoast-seo-wordpress\/ -->\n<title>Questions-r\u00e9ponses de l&#039;auteur\u00a0: Zofia Reych de Born to Climb - Climashield\u00ae<\/title>\n<meta name=\"description\" content=\"Nous avons rencontr\u00e9 l&#039;anthropologue et grimpeuse Zofia Reych \u00e0 propos de son nouveau livre Born to Climb.\" \/>\n<meta name=\"robots\" content=\"index, follow, max-snippet:-1, max-image-preview:large, max-video-preview:-1\" \/>\n<link rel=\"canonical\" href=\"https:\/\/climashield.com\/fr\/author-qa-born-to-climbs-zofia-reych\/\" \/>\n<meta property=\"og:locale\" content=\"fr_FR\" \/>\n<meta property=\"og:type\" content=\"article\" \/>\n<meta property=\"og:title\" content=\"Questions-r\u00e9ponses de l&#039;auteur\u00a0: Zofia Reych de Born to Climb - Climashield\u00ae\" \/>\n<meta property=\"og:description\" content=\"Nous avons rencontr\u00e9 l&#039;anthropologue et grimpeuse Zofia Reych \u00e0 propos de son nouveau livre Born to Climb.\" \/>\n<meta property=\"og:url\" content=\"https:\/\/climashield.com\/fr\/author-qa-born-to-climbs-zofia-reych\/\" \/>\n<meta property=\"og:site_name\" content=\"Climashield\u00ae - Continuous Filament Insulation\" \/>\n<meta property=\"article:publisher\" content=\"https:\/\/www.facebook.com\/Climashield\" \/>\n<meta property=\"article:published_time\" content=\"2023-03-02T02:35:04+00:00\" \/>\n<meta property=\"article:modified_time\" content=\"2025-09-05T23:56:27+00:00\" \/>\n<meta property=\"og:image\" content=\"https:\/\/climashield.com\/wp-content\/uploads\/2023\/03\/Zofia_Reych_climbing_barefoot_Andy_Day_3902x-scaled.webp\" \/>\n\t<meta property=\"og:image:width\" content=\"2000\" \/>\n\t<meta property=\"og:image:height\" content=\"1111\" \/>\n\t<meta property=\"og:image:type\" content=\"image\/webp\" \/>\n<meta name=\"author\" content=\"christi.hardin\" \/>\n<meta name=\"twitter:card\" content=\"summary_large_image\" \/>\n<meta name=\"twitter:creator\" content=\"@ClimashieldUSA\" \/>\n<meta name=\"twitter:site\" content=\"@ClimashieldUSA\" \/>\n<meta name=\"twitter:label1\" content=\"\u00c9crit par\" \/>\n\t<meta name=\"twitter:data1\" content=\"christi.hardin\" \/>\n\t<meta name=\"twitter:label2\" content=\"Dur\u00e9e de lecture estim\u00e9e\" \/>\n\t<meta name=\"twitter:data2\" content=\"5 minutes\" \/>\n<script type=\"application\/ld+json\" class=\"yoast-schema-graph\">{\"@context\":\"https:\\\/\\\/schema.org\",\"@graph\":[{\"@type\":\"Article\",\"@id\":\"https:\\\/\\\/climashield.com\\\/fr\\\/author-qa-born-to-climbs-zofia-reych\\\/#article\",\"isPartOf\":{\"@id\":\"https:\\\/\\\/climashield.com\\\/fr\\\/author-qa-born-to-climbs-zofia-reych\\\/\"},\"author\":{\"name\":\"christi.hardin\",\"@id\":\"https:\\\/\\\/climashield.com\\\/fr\\\/#\\\/schema\\\/person\\\/3d7a616ff71140bb3c783453cabb372e\"},\"headline\":\"Questions-r\u00e9ponses de l&rsquo;auteur\u00a0: Zofia Reych de Born to Climb\",\"datePublished\":\"2023-03-02T02:35:04+00:00\",\"dateModified\":\"2025-09-05T23:56:27+00:00\",\"mainEntityOfPage\":{\"@id\":\"https:\\\/\\\/climashield.com\\\/fr\\\/author-qa-born-to-climbs-zofia-reych\\\/\"},\"wordCount\":1086,\"publisher\":{\"@id\":\"https:\\\/\\\/climashield.com\\\/fr\\\/#organization\"},\"image\":{\"@id\":\"https:\\\/\\\/climashield.com\\\/fr\\\/author-qa-born-to-climbs-zofia-reych\\\/#primaryimage\"},\"thumbnailUrl\":\"https:\\\/\\\/climashield.com\\\/wp-content\\\/uploads\\\/2023\\\/03\\\/Zofia_Reych_climbing_barefoot_Andy_Day_3902x-scaled.webp\",\"keywords\":[\"Climalife\",\"Sortez\"],\"articleSection\":[\"Durabilit\u00e9\",\"Plaidoyer\"],\"inLanguage\":\"fr-FR\"},{\"@type\":\"WebPage\",\"@id\":\"https:\\\/\\\/climashield.com\\\/fr\\\/author-qa-born-to-climbs-zofia-reych\\\/\",\"url\":\"https:\\\/\\\/climashield.com\\\/fr\\\/author-qa-born-to-climbs-zofia-reych\\\/\",\"name\":\"Questions-r\u00e9ponses de l'auteur\u00a0: Zofia Reych de Born to Climb - Climashield\u00ae\",\"isPartOf\":{\"@id\":\"https:\\\/\\\/climashield.com\\\/fr\\\/#website\"},\"primaryImageOfPage\":{\"@id\":\"https:\\\/\\\/climashield.com\\\/fr\\\/author-qa-born-to-climbs-zofia-reych\\\/#primaryimage\"},\"image\":{\"@id\":\"https:\\\/\\\/climashield.com\\\/fr\\\/author-qa-born-to-climbs-zofia-reych\\\/#primaryimage\"},\"thumbnailUrl\":\"https:\\\/\\\/climashield.com\\\/wp-content\\\/uploads\\\/2023\\\/03\\\/Zofia_Reych_climbing_barefoot_Andy_Day_3902x-scaled.webp\",\"datePublished\":\"2023-03-02T02:35:04+00:00\",\"dateModified\":\"2025-09-05T23:56:27+00:00\",\"description\":\"Nous avons rencontr\u00e9 l'anthropologue et grimpeuse Zofia Reych \u00e0 propos de son nouveau livre Born to Climb.\",\"breadcrumb\":{\"@id\":\"https:\\\/\\\/climashield.com\\\/fr\\\/author-qa-born-to-climbs-zofia-reych\\\/#breadcrumb\"},\"inLanguage\":\"fr-FR\",\"potentialAction\":[{\"@type\":\"ReadAction\",\"target\":[\"https:\\\/\\\/climashield.com\\\/fr\\\/author-qa-born-to-climbs-zofia-reych\\\/\"]}]},{\"@type\":\"ImageObject\",\"inLanguage\":\"fr-FR\",\"@id\":\"https:\\\/\\\/climashield.com\\\/fr\\\/author-qa-born-to-climbs-zofia-reych\\\/#primaryimage\",\"url\":\"https:\\\/\\\/climashield.com\\\/wp-content\\\/uploads\\\/2023\\\/03\\\/Zofia_Reych_climbing_barefoot_Andy_Day_3902x-scaled.webp\",\"contentUrl\":\"https:\\\/\\\/climashield.com\\\/wp-content\\\/uploads\\\/2023\\\/03\\\/Zofia_Reych_climbing_barefoot_Andy_Day_3902x-scaled.webp\",\"width\":2000,\"height\":1111,\"caption\":\"Zofia Reych climbing barefoot\"},{\"@type\":\"BreadcrumbList\",\"@id\":\"https:\\\/\\\/climashield.com\\\/fr\\\/author-qa-born-to-climbs-zofia-reych\\\/#breadcrumb\",\"itemListElement\":[{\"@type\":\"ListItem\",\"position\":1,\"name\":\"Home\",\"item\":\"https:\\\/\\\/climashield.com\\\/fr\\\/home\\\/\"},{\"@type\":\"ListItem\",\"position\":2,\"name\":\"Questions-r\u00e9ponses de l&#8217;auteur\u00a0: Zofia Reych de Born to Climb\"}]},{\"@type\":\"WebSite\",\"@id\":\"https:\\\/\\\/climashield.com\\\/fr\\\/#website\",\"url\":\"https:\\\/\\\/climashield.com\\\/fr\\\/\",\"name\":\"Climashield\u00ae - Continuous Filament Insulation\",\"description\":\"Climashield\u00ae is the world leader in the manufacture and development of continuous filament insulation. More than just a brand name, we engineer new technologies and innovate breakthrough performance.\",\"publisher\":{\"@id\":\"https:\\\/\\\/climashield.com\\\/fr\\\/#organization\"},\"potentialAction\":[{\"@type\":\"SearchAction\",\"target\":{\"@type\":\"EntryPoint\",\"urlTemplate\":\"https:\\\/\\\/climashield.com\\\/fr\\\/?s={search_term_string}\"},\"query-input\":{\"@type\":\"PropertyValueSpecification\",\"valueRequired\":true,\"valueName\":\"search_term_string\"}}],\"inLanguage\":\"fr-FR\"},{\"@type\":\"Organization\",\"@id\":\"https:\\\/\\\/climashield.com\\\/fr\\\/#organization\",\"name\":\"Climashield\",\"url\":\"https:\\\/\\\/climashield.com\\\/fr\\\/\",\"logo\":{\"@type\":\"ImageObject\",\"inLanguage\":\"fr-FR\",\"@id\":\"https:\\\/\\\/climashield.com\\\/fr\\\/#\\\/schema\\\/logo\\\/image\\\/\",\"url\":\"https:\\\/\\\/climashield.com\\\/wp-content\\\/uploads\\\/2021\\\/03\\\/climashield-logo-red.jpg\",\"contentUrl\":\"https:\\\/\\\/climashield.com\\\/wp-content\\\/uploads\\\/2021\\\/03\\\/climashield-logo-red.jpg\",\"width\":422,\"height\":66,\"caption\":\"Climashield\"},\"image\":{\"@id\":\"https:\\\/\\\/climashield.com\\\/fr\\\/#\\\/schema\\\/logo\\\/image\\\/\"},\"sameAs\":[\"https:\\\/\\\/www.facebook.com\\\/Climashield\",\"https:\\\/\\\/x.com\\\/ClimashieldUSA\",\"https:\\\/\\\/www.instagram.com\\\/climashieldusa\\\/\"]},{\"@type\":\"Person\",\"@id\":\"https:\\\/\\\/climashield.com\\\/fr\\\/#\\\/schema\\\/person\\\/3d7a616ff71140bb3c783453cabb372e\",\"name\":\"christi.hardin\",\"image\":{\"@type\":\"ImageObject\",\"inLanguage\":\"fr-FR\",\"@id\":\"https:\\\/\\\/secure.gravatar.com\\\/avatar\\\/4e7c695ba24b8c627aa64f71fb4d89b5ec2a66da0be574a47f7e92f1e6b82ffb?s=96&d=mm&r=g\",\"url\":\"https:\\\/\\\/secure.gravatar.com\\\/avatar\\\/4e7c695ba24b8c627aa64f71fb4d89b5ec2a66da0be574a47f7e92f1e6b82ffb?s=96&d=mm&r=g\",\"contentUrl\":\"https:\\\/\\\/secure.gravatar.com\\\/avatar\\\/4e7c695ba24b8c627aa64f71fb4d89b5ec2a66da0be574a47f7e92f1e6b82ffb?s=96&d=mm&r=g\",\"caption\":\"christi.hardin\"}}]}<\/script>\n<!-- \/ Yoast SEO plugin. -->","yoast_head_json":{"title":"Questions-r\u00e9ponses de l'auteur\u00a0: Zofia Reych de Born to Climb - Climashield\u00ae","description":"Nous avons rencontr\u00e9 l'anthropologue et grimpeuse Zofia Reych \u00e0 propos de son nouveau livre Born to Climb.","robots":{"index":"index","follow":"follow","max-snippet":"max-snippet:-1","max-image-preview":"max-image-preview:large","max-video-preview":"max-video-preview:-1"},"canonical":"https:\/\/climashield.com\/fr\/author-qa-born-to-climbs-zofia-reych\/","og_locale":"fr_FR","og_type":"article","og_title":"Questions-r\u00e9ponses de l'auteur\u00a0: Zofia Reych de Born to Climb - Climashield\u00ae","og_description":"Nous avons rencontr\u00e9 l'anthropologue et grimpeuse Zofia Reych \u00e0 propos de son nouveau livre Born to Climb.","og_url":"https:\/\/climashield.com\/fr\/author-qa-born-to-climbs-zofia-reych\/","og_site_name":"Climashield\u00ae - Continuous Filament Insulation","article_publisher":"https:\/\/www.facebook.com\/Climashield","article_published_time":"2023-03-02T02:35:04+00:00","article_modified_time":"2025-09-05T23:56:27+00:00","og_image":[{"width":2000,"height":1111,"url":"https:\/\/climashield.com\/wp-content\/uploads\/2023\/03\/Zofia_Reych_climbing_barefoot_Andy_Day_3902x-scaled.webp","type":"image\/webp"}],"author":"christi.hardin","twitter_card":"summary_large_image","twitter_creator":"@ClimashieldUSA","twitter_site":"@ClimashieldUSA","twitter_misc":{"\u00c9crit par":"christi.hardin","Dur\u00e9e de lecture estim\u00e9e":"5 minutes"},"schema":{"@context":"https:\/\/schema.org","@graph":[{"@type":"Article","@id":"https:\/\/climashield.com\/fr\/author-qa-born-to-climbs-zofia-reych\/#article","isPartOf":{"@id":"https:\/\/climashield.com\/fr\/author-qa-born-to-climbs-zofia-reych\/"},"author":{"name":"christi.hardin","@id":"https:\/\/climashield.com\/fr\/#\/schema\/person\/3d7a616ff71140bb3c783453cabb372e"},"headline":"Questions-r\u00e9ponses de l&rsquo;auteur\u00a0: Zofia Reych de Born to Climb","datePublished":"2023-03-02T02:35:04+00:00","dateModified":"2025-09-05T23:56:27+00:00","mainEntityOfPage":{"@id":"https:\/\/climashield.com\/fr\/author-qa-born-to-climbs-zofia-reych\/"},"wordCount":1086,"publisher":{"@id":"https:\/\/climashield.com\/fr\/#organization"},"image":{"@id":"https:\/\/climashield.com\/fr\/author-qa-born-to-climbs-zofia-reych\/#primaryimage"},"thumbnailUrl":"https:\/\/climashield.com\/wp-content\/uploads\/2023\/03\/Zofia_Reych_climbing_barefoot_Andy_Day_3902x-scaled.webp","keywords":["Climalife","Sortez"],"articleSection":["Durabilit\u00e9","Plaidoyer"],"inLanguage":"fr-FR"},{"@type":"WebPage","@id":"https:\/\/climashield.com\/fr\/author-qa-born-to-climbs-zofia-reych\/","url":"https:\/\/climashield.com\/fr\/author-qa-born-to-climbs-zofia-reych\/","name":"Questions-r\u00e9ponses de l'auteur\u00a0: Zofia Reych de Born to Climb - Climashield\u00ae","isPartOf":{"@id":"https:\/\/climashield.com\/fr\/#website"},"primaryImageOfPage":{"@id":"https:\/\/climashield.com\/fr\/author-qa-born-to-climbs-zofia-reych\/#primaryimage"},"image":{"@id":"https:\/\/climashield.com\/fr\/author-qa-born-to-climbs-zofia-reych\/#primaryimage"},"thumbnailUrl":"https:\/\/climashield.com\/wp-content\/uploads\/2023\/03\/Zofia_Reych_climbing_barefoot_Andy_Day_3902x-scaled.webp","datePublished":"2023-03-02T02:35:04+00:00","dateModified":"2025-09-05T23:56:27+00:00","description":"Nous avons rencontr\u00e9 l'anthropologue et grimpeuse Zofia Reych \u00e0 propos de son nouveau livre Born to Climb.","breadcrumb":{"@id":"https:\/\/climashield.com\/fr\/author-qa-born-to-climbs-zofia-reych\/#breadcrumb"},"inLanguage":"fr-FR","potentialAction":[{"@type":"ReadAction","target":["https:\/\/climashield.com\/fr\/author-qa-born-to-climbs-zofia-reych\/"]}]},{"@type":"ImageObject","inLanguage":"fr-FR","@id":"https:\/\/climashield.com\/fr\/author-qa-born-to-climbs-zofia-reych\/#primaryimage","url":"https:\/\/climashield.com\/wp-content\/uploads\/2023\/03\/Zofia_Reych_climbing_barefoot_Andy_Day_3902x-scaled.webp","contentUrl":"https:\/\/climashield.com\/wp-content\/uploads\/2023\/03\/Zofia_Reych_climbing_barefoot_Andy_Day_3902x-scaled.webp","width":2000,"height":1111,"caption":"Zofia Reych climbing barefoot"},{"@type":"BreadcrumbList","@id":"https:\/\/climashield.com\/fr\/author-qa-born-to-climbs-zofia-reych\/#breadcrumb","itemListElement":[{"@type":"ListItem","position":1,"name":"Home","item":"https:\/\/climashield.com\/fr\/home\/"},{"@type":"ListItem","position":2,"name":"Questions-r\u00e9ponses de l&#8217;auteur\u00a0: Zofia Reych de Born to Climb"}]},{"@type":"WebSite","@id":"https:\/\/climashield.com\/fr\/#website","url":"https:\/\/climashield.com\/fr\/","name":"Climashield\u00ae - Continuous Filament Insulation","description":"Climashield\u00ae is the world leader in the manufacture and development of continuous filament insulation. More than just a brand name, we engineer new technologies and innovate breakthrough performance.","publisher":{"@id":"https:\/\/climashield.com\/fr\/#organization"},"potentialAction":[{"@type":"SearchAction","target":{"@type":"EntryPoint","urlTemplate":"https:\/\/climashield.com\/fr\/?s={search_term_string}"},"query-input":{"@type":"PropertyValueSpecification","valueRequired":true,"valueName":"search_term_string"}}],"inLanguage":"fr-FR"},{"@type":"Organization","@id":"https:\/\/climashield.com\/fr\/#organization","name":"Climashield","url":"https:\/\/climashield.com\/fr\/","logo":{"@type":"ImageObject","inLanguage":"fr-FR","@id":"https:\/\/climashield.com\/fr\/#\/schema\/logo\/image\/","url":"https:\/\/climashield.com\/wp-content\/uploads\/2021\/03\/climashield-logo-red.jpg","contentUrl":"https:\/\/climashield.com\/wp-content\/uploads\/2021\/03\/climashield-logo-red.jpg","width":422,"height":66,"caption":"Climashield"},"image":{"@id":"https:\/\/climashield.com\/fr\/#\/schema\/logo\/image\/"},"sameAs":["https:\/\/www.facebook.com\/Climashield","https:\/\/x.com\/ClimashieldUSA","https:\/\/www.instagram.com\/climashieldusa\/"]},{"@type":"Person","@id":"https:\/\/climashield.com\/fr\/#\/schema\/person\/3d7a616ff71140bb3c783453cabb372e","name":"christi.hardin","image":{"@type":"ImageObject","inLanguage":"fr-FR","@id":"https:\/\/secure.gravatar.com\/avatar\/4e7c695ba24b8c627aa64f71fb4d89b5ec2a66da0be574a47f7e92f1e6b82ffb?s=96&d=mm&r=g","url":"https:\/\/secure.gravatar.com\/avatar\/4e7c695ba24b8c627aa64f71fb4d89b5ec2a66da0be574a47f7e92f1e6b82ffb?s=96&d=mm&r=g","contentUrl":"https:\/\/secure.gravatar.com\/avatar\/4e7c695ba24b8c627aa64f71fb4d89b5ec2a66da0be574a47f7e92f1e6b82ffb?s=96&d=mm&r=g","caption":"christi.hardin"}}]}},"_links":{"self":[{"href":"https:\/\/climashield.com\/fr\/wp-json\/wp\/v2\/posts\/5158","targetHints":{"allow":["GET"]}}],"collection":[{"href":"https:\/\/climashield.com\/fr\/wp-json\/wp\/v2\/posts"}],"about":[{"href":"https:\/\/climashield.com\/fr\/wp-json\/wp\/v2\/types\/post"}],"author":[{"embeddable":true,"href":"https:\/\/climashield.com\/fr\/wp-json\/wp\/v2\/users\/4"}],"replies":[{"embeddable":true,"href":"https:\/\/climashield.com\/fr\/wp-json\/wp\/v2\/comments?post=5158"}],"version-history":[{"count":0,"href":"https:\/\/climashield.com\/fr\/wp-json\/wp\/v2\/posts\/5158\/revisions"}],"wp:featuredmedia":[{"embeddable":true,"href":"https:\/\/climashield.com\/fr\/wp-json\/wp\/v2\/media\/5166"}],"wp:attachment":[{"href":"https:\/\/climashield.com\/fr\/wp-json\/wp\/v2\/media?parent=5158"}],"wp:term":[{"taxonomy":"category","embeddable":true,"href":"https:\/\/climashield.com\/fr\/wp-json\/wp\/v2\/categories?post=5158"},{"taxonomy":"post_tag","embeddable":true,"href":"https:\/\/climashield.com\/fr\/wp-json\/wp\/v2\/tags?post=5158"}],"curies":[{"name":"wp","href":"https:\/\/api.w.org\/{rel}","templated":true}]}}